{"id":1540,"date":"2023-01-24T17:39:32","date_gmt":"2023-01-24T17:39:32","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/old-lords-splendor\/"},"modified":"2026-05-13T15:39:31","modified_gmt":"2026-05-13T13:39:31","slug":"%e6%98%94%e3%81%ae%e9%a0%98%e4%b8%bb%e3%81%ae%e6%a0%84%e5%85%89","status":"publish","type":"product","link":"https:\/\/mail.cyclingjerseys-originals.com\/ja\/retro-wielershirt\/old-lords-splendor\/","title":{"rendered":"\u30aa\u30fc\u30eb\u30c9 \u30ed\u30fc\u30ba-\u30b9\u30d7\u30ec\u30f3\u30c0\u30fc 1978 \u30b5\u30a4\u30af\u30eb \u30b7\u30e3\u30c4"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1539,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-1540","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>OLD LORDS-SPLENDOR  1978                                 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/old-lords-splendor\/\" \/>\n<meta property=\"og:locale\" content=\"ja_JP\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"OLD LORDS-SPLENDOR  1978                                 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/old-lords-splendor\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:39:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/SSA45095.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u5206\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/old-lords-splendor\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/old-lords-splendor\\\/\",\"name\":\"OLD LORDS-SPLENDOR 1978 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/old-lords-splendor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/old-lords-splendor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA45095.jpg\",\"datePublished\":\"2023-01-24T17:39:32+00:00\",\"dateModified\":\"2026-05-13T13:39:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/old-lords-splendor\\\/#breadcrumb\"},\"inLanguage\":\"ja\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/old-lords-splendor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/old-lords-splendor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA45095.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA45095.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/de\\\/retro-wielershirt\\\/old-lords-splendor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"OLD LORDS-SPLENDOR 1978 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ja\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ja\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"OLD LORDS-SPLENDOR 1978 CYCLING SHIRT - Ton Merckx \u30b5\u30a4\u30af\u30eb \u30b8\u30e3\u30fc\u30b8 - \u30b5\u30a4\u30af\u30eb \u30b8\u30e3\u30fc\u30b8\u306e\u4e16\u754c\u3092\u5de1\u308b\u30c4\u30a2\u30fc","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/old-lords-splendor\/","og_locale":"ja_JP","og_type":"article","og_title":"OLD LORDS-SPLENDOR  1978                                 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/old-lords-splendor\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:39:31+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/SSA45095.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"\u63a8\u5b9a\u8aad\u307f\u53d6\u308a\u6642\u9593":"1\u5206"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/old-lords-splendor\/","url":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/old-lords-splendor\/","name":"OLD LORDS-SPLENDOR 1978 CYCLING SHIRT - Ton Merckx \u30b5\u30a4\u30af\u30eb \u30b8\u30e3\u30fc\u30b8 - \u30b5\u30a4\u30af\u30eb \u30b8\u30e3\u30fc\u30b8\u306e\u4e16\u754c\u3092\u5de1\u308b\u30c4\u30a2\u30fc","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/old-lords-splendor\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/old-lords-splendor\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/SSA45095.jpg","datePublished":"2023-01-24T17:39:32+00:00","dateModified":"2026-05-13T13:39:31+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/old-lords-splendor\/#breadcrumb"},"inLanguage":"ja","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/old-lords-splendor\/"]}]},{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/old-lords-splendor\/#primaryimage","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/SSA45095.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/SSA45095.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/de\/retro-wielershirt\/old-lords-splendor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"OLD LORDS-SPLENDOR 1978 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Ton Merckx \u30b5\u30a4\u30af\u30eb \u30b7\u30e3\u30c4 - \u30b5\u30a4\u30af\u30eb \u30b7\u30e3\u30c4\u306e\u4e16\u754c\u3092\u5de1\u308b\u30c4\u30a2\u30fc","description":"\u4f55\u5343\u3082\u306e\u30aa\u30ea\u30b8\u30ca\u30eb \u30b5\u30a4\u30af\u30ea\u30f3\u30b0 \u30b8\u30e3\u30fc\u30b8 - \u30ec\u30d7\u30ea\u30ab\u3092\u6ce8\u6587\u3057\u3066\u304f\u3060\u3055\u3044!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ja"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Ton Merckx \u30b5\u30a4\u30af\u30eb \u30b7\u30e3\u30c4 - \u30b5\u30a4\u30af\u30eb \u30b7\u30e3\u30c4\u306e\u4e16\u754c\u3092\u5de1\u308b\u30c4\u30a2\u30fc","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"ja","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/ja\/wp-json\/wp\/v2\/product\/1540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/ja\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/ja\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/ja\/wp-json\/wp\/v2\/media\/1539"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/ja\/wp-json\/wp\/v2\/media?parent=1540"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/ja\/wp-json\/wp\/v2\/product_brand?post=1540"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/ja\/wp-json\/wp\/v2\/product_cat?post=1540"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/ja\/wp-json\/wp\/v2\/product_tag?post=1540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}