{"id":686,"date":"2023-01-24T17:29:35","date_gmt":"2023-01-24T17:29:35","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/leiderstrui-algemeen-klassement\/"},"modified":"2026-05-13T15:40:07","modified_gmt":"2026-05-13T13:40:07","slug":"maglia-di-leader-della-classifica-generale","status":"publish","type":"product","link":"https:\/\/mail.cyclingjerseys-originals.com\/it\/retro-wielershirt\/leiderstrui-algemeen-klassement\/","title":{"rendered":"ARCTIC RACE OF NORWAY \u2013 CLASSIFICA GENERALE MAGLIA LEADER \u2013 2021 \u2013 MAGLIA DA CICLISMO"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":416,"template":"","meta":[],"product_brand":[],"product_cat":[54],"product_tag":[],"class_list":["post-686","product","type-product","status-publish","has-post-thumbnail","product_cat-leiderstruien","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ARCTIC RACE OF NORWAY - LEIDERSTRUI ALGEMEEN KLASSEMENT - 2021 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/maglia-di-leader-della-classifica-generale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ARCTIC RACE OF NORWAY - LEIDERSTRUI ALGEMEEN KLASSEMENT - 2021 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/maglia-di-leader-della-classifica-generale\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:40:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_1069-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/maglia-da-ciclismo-retro\\\/maglia-di-leader-della-classifica-generale\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/maglia-da-ciclismo-retro\\\/maglia-di-leader-della-classifica-generale\\\/\",\"name\":\"ARCTIC RACE OF NORWAY - LEIDERSTRUI ALGEMEEN KLASSEMENT - 2021 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/maglia-da-ciclismo-retro\\\/maglia-di-leader-della-classifica-generale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/maglia-da-ciclismo-retro\\\/maglia-di-leader-della-classifica-generale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_1069-scaled.jpg\",\"datePublished\":\"2023-01-24T17:29:35+00:00\",\"dateModified\":\"2026-05-13T13:40:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/maglia-da-ciclismo-retro\\\/maglia-di-leader-della-classifica-generale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/maglia-da-ciclismo-retro\\\/maglia-di-leader-della-classifica-generale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/maglia-da-ciclismo-retro\\\/maglia-di-leader-della-classifica-generale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_1069-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_1069-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/maglia-da-ciclismo-retro\\\/maglia-di-leader-della-classifica-generale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ARCTIC RACE OF NORWAY &#8211; LEIDERSTRUI ALGEMEEN KLASSEMENT &#8211; 2021 &#8211; WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ARCTIC RACE OF NORWAY - CLASSIFICA GENERALE MAGLIA LEADER - 2021 - MAGLIA CICLISMO - Maglie ciclismo Ton Merckx - Tour nel mondo delle maglie ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/maglia-di-leader-della-classifica-generale\/","og_locale":"it_IT","og_type":"article","og_title":"ARCTIC RACE OF NORWAY - LEIDERSTRUI ALGEMEEN KLASSEMENT - 2021 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/maglia-di-leader-della-classifica-generale\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:40:07+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_1069-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/maglia-di-leader-della-classifica-generale\/","url":"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/maglia-di-leader-della-classifica-generale\/","name":"ARCTIC RACE OF NORWAY - CLASSIFICA GENERALE MAGLIA LEADER - 2021 - MAGLIA CICLISMO - Maglie ciclismo Ton Merckx - Tour nel mondo delle maglie ciclismo","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/maglia-di-leader-della-classifica-generale\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/maglia-di-leader-della-classifica-generale\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_1069-scaled.jpg","datePublished":"2023-01-24T17:29:35+00:00","dateModified":"2026-05-13T13:40:07+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/maglia-di-leader-della-classifica-generale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/maglia-di-leader-della-classifica-generale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/maglia-di-leader-della-classifica-generale\/#primaryimage","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_1069-scaled.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_1069-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/it\/maglia-da-ciclismo-retro\/maglia-di-leader-della-classifica-generale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"ARCTIC RACE OF NORWAY &#8211; LEIDERSTRUI ALGEMEEN KLASSEMENT &#8211; 2021 &#8211; WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","description":"migliaia di maglie da ciclismo originali - ordina la tua replica!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product\/686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/media\/416"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/media?parent=686"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product_brand?post=686"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product_cat?post=686"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product_tag?post=686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}