{"id":1730,"date":"2023-01-24T17:41:30","date_gmt":"2023-01-24T17:41:30","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/silence-lotto-ridley\/"},"modified":"2026-05-13T15:39:22","modified_gmt":"2026-05-13T13:39:22","slug":"silenzio-lotto-ridley","status":"publish","type":"product","link":"https:\/\/mail.cyclingjerseys-originals.com\/it\/retro-wielershirt\/silence-lotto-ridley\/","title":{"rendered":"MAGLIA DA CICLISMO LOTTO (lb)-SILENCE-BRUSTOR 2008"},"content":{"rendered":"<p>Nel 2008, OMEGA PHARMA ha deciso di promuovere il marchio SILENCE, un farmaco antirussamento.<\/p>\n<p>La storia racconta che in una delle prime gare dell&#039;anno ciclistico 2008, quando i corridori di SILENCE-LOTTO cavalcavano in testa al gruppo, si ud\u00ec un russare massiccio dal gruppo. Umorismo ciclistico al suo meglio.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nel 2008, OMEGA PHARMA decise di promuovere il suo farmaco antirussamento, SILENCE. La storia narra che durante una delle prime gare dell&#039;anno ciclistico 2008, quando i corridori del team SILENCE-LOTTO presero il comando, un forte russare si diffuse tra il gruppo. Umorismo ciclistico al suo meglio.<\/p>","protected":false},"featured_media":177419,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-1730","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LOTTO (lb)-SILENCE-BRUSTOR 2008 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ton.connectingminds.net\/es\/retro-wielershirt\/silence-lotto-ridley\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LOTTO (lb)-SILENCE-BRUSTOR 2008 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"In 2008 besloot OMEGA PHARMA het merk SILENCE onder de aandacht te brengen, een anti-snurkmedicijn. Het verhaal gaat dat bij een van de eerste koersen van het wielerjaar 2008, toen er renners van SILENCE-LOTTO op kop van het peloton kwamen rijden, vanuit het peloton een massaal gesnurk klonk.\u00a0 Wielerhumor ten top.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ton.connectingminds.net\/es\/retro-wielershirt\/silence-lotto-ridley\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:39:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ton.connectingminds.net\/wp-content\/uploads\/2023\/01\/IMG_4512-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/es\\\/retro-wielershirt\\\/silence-lotto-ridley\\\/\",\"url\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/es\\\/retro-wielershirt\\\/silence-lotto-ridley\\\/\",\"name\":\"LOTTO (lb)-SILENCE-BRUSTOR 2008 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/es\\\/retro-wielershirt\\\/silence-lotto-ridley\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/es\\\/retro-wielershirt\\\/silence-lotto-ridley\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4512-scaled.jpg\",\"datePublished\":\"2023-01-24T17:41:30+00:00\",\"dateModified\":\"2026-05-13T13:39:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/es\\\/retro-wielershirt\\\/silence-lotto-ridley\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ton.connectingminds.net\\\/es\\\/retro-wielershirt\\\/silence-lotto-ridley\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/es\\\/retro-wielershirt\\\/silence-lotto-ridley\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4512-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4512-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ton.connectingminds.net\\\/es\\\/retro-wielershirt\\\/silence-lotto-ridley\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LOTTO (lb)-SILENCE-BRUSTOR 2008 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MAGLIA CICLISMO LOTTO (lb)-SILENCE-BRUSTOR 2008 - Maglie ciclismo Ton Merckx - Viaggio nel mondo delle maglie ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ton.connectingminds.net\/es\/retro-wielershirt\/silence-lotto-ridley\/","og_locale":"it_IT","og_type":"article","og_title":"LOTTO (lb)-SILENCE-BRUSTOR 2008 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"In 2008 besloot OMEGA PHARMA het merk SILENCE onder de aandacht te brengen, een anti-snurkmedicijn. Het verhaal gaat dat bij een van de eerste koersen van het wielerjaar 2008, toen er renners van SILENCE-LOTTO op kop van het peloton kwamen rijden, vanuit het peloton een massaal gesnurk klonk.\u00a0 Wielerhumor ten top.","og_url":"https:\/\/www.ton.connectingminds.net\/es\/retro-wielershirt\/silence-lotto-ridley\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:39:22+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/www.ton.connectingminds.net\/wp-content\/uploads\/2023\/01\/IMG_4512-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ton.connectingminds.net\/es\/retro-wielershirt\/silence-lotto-ridley\/","url":"https:\/\/www.ton.connectingminds.net\/es\/retro-wielershirt\/silence-lotto-ridley\/","name":"MAGLIA CICLISMO LOTTO (lb)-SILENCE-BRUSTOR 2008 - Maglie ciclismo Ton Merckx - Viaggio nel mondo delle maglie ciclismo","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ton.connectingminds.net\/es\/retro-wielershirt\/silence-lotto-ridley\/#primaryimage"},"image":{"@id":"https:\/\/www.ton.connectingminds.net\/es\/retro-wielershirt\/silence-lotto-ridley\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_4512-scaled.jpg","datePublished":"2023-01-24T17:41:30+00:00","dateModified":"2026-05-13T13:39:22+00:00","breadcrumb":{"@id":"https:\/\/www.ton.connectingminds.net\/es\/retro-wielershirt\/silence-lotto-ridley\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ton.connectingminds.net\/es\/retro-wielershirt\/silence-lotto-ridley\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.ton.connectingminds.net\/es\/retro-wielershirt\/silence-lotto-ridley\/#primaryimage","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_4512-scaled.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_4512-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/www.ton.connectingminds.net\/es\/retro-wielershirt\/silence-lotto-ridley\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"LOTTO (lb)-SILENCE-BRUSTOR 2008 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","description":"migliaia di maglie da ciclismo originali - ordina la tua replica!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product\/1730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/media\/177419"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/media?parent=1730"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product_brand?post=1730"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product_cat?post=1730"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product_tag?post=1730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}