{"id":1145,"date":"2023-01-24T17:35:23","date_gmt":"2023-01-24T17:35:23","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/fiat-jack\/"},"modified":"2026-05-13T15:39:48","modified_gmt":"2026-05-13T13:39:48","slug":"cric-fiat","status":"publish","type":"product","link":"https:\/\/mail.cyclingjerseys-originals.com\/it\/retro-wielershirt\/fiat-jack\/","title":{"rendered":"GIACCA DA CICLISMO FIAT (b) 1977"},"content":{"rendered":"<p>FIAT 1977<\/p>","protected":false},"excerpt":{"rendered":"<p>FIAT 1977<\/p>","protected":false},"featured_media":33354,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-1145","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FIAT (b)  1977                                               WIELERJACK - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/fiat-jack\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FIAT (b)  1977                                               WIELERJACK - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"FIAT\u00a0 \u00a01977\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/fiat-jack\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:39:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_3119-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/es\\\/retro-wielershirt\\\/fiat-jack\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/es\\\/retro-wielershirt\\\/fiat-jack\\\/\",\"name\":\"FIAT (b) 1977 WIELERJACK - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/es\\\/retro-wielershirt\\\/fiat-jack\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/es\\\/retro-wielershirt\\\/fiat-jack\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_3119-scaled.jpg\",\"datePublished\":\"2023-01-24T17:35:23+00:00\",\"dateModified\":\"2026-05-13T13:39:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/es\\\/retro-wielershirt\\\/fiat-jack\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/es\\\/retro-wielershirt\\\/fiat-jack\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/es\\\/retro-wielershirt\\\/fiat-jack\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_3119-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_3119-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"FIAT 1977\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/es\\\/retro-wielershirt\\\/fiat-jack\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"FIAT (b) 1977 WIELERJACK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GIACCA CICLISMO FIAT (b) 1977 - Maglie ciclismo Ton Merckx - Viaggio nel mondo delle maglie ciclismo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/fiat-jack\/","og_locale":"it_IT","og_type":"article","og_title":"FIAT (b)  1977                                               WIELERJACK - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"FIAT\u00a0 \u00a01977","og_url":"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/fiat-jack\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:39:48+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_3119-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/fiat-jack\/","url":"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/fiat-jack\/","name":"GIACCA CICLISMO FIAT (b) 1977 - Maglie ciclismo Ton Merckx - Viaggio nel mondo delle maglie ciclismo","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/fiat-jack\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/fiat-jack\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_3119-scaled.jpg","datePublished":"2023-01-24T17:35:23+00:00","dateModified":"2026-05-13T13:39:48+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/fiat-jack\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/fiat-jack\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/fiat-jack\/#primaryimage","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_3119-scaled.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_3119-scaled.jpg","width":1920,"height":2560,"caption":"FIAT 1977"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/es\/retro-wielershirt\/fiat-jack\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"FIAT (b) 1977 WIELERJACK"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","description":"migliaia di maglie da ciclismo originali - ordina la tua replica!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Magliette da ciclismo Ton Merckx - Tour nel mondo delle magliette da ciclismo","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product\/1145","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/media\/33354"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/media?parent=1145"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product_brand?post=1145"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product_cat?post=1145"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/it\/wp-json\/wp\/v2\/product_tag?post=1145"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}