{"id":2574,"date":"2023-01-24T17:51:38","date_gmt":"2023-01-24T17:51:38","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/ag2r-decathlon\/"},"modified":"2026-05-13T15:38:48","modified_gmt":"2026-05-13T13:38:48","slug":"decathlon-ag2r","status":"publish","type":"product","link":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/ag2r-decathlon\/","title":{"rendered":"AG2R (b) MAILLOT DE CYCLISME PREVOYANCE-DECATHLON 2002"},"content":{"rendered":"<p>AG2R PR\u00c9VOYANCE D\u00c9CATHLON 2002<\/p>","protected":false},"excerpt":{"rendered":"<p>AG2R PR\u00c9VOYANCE D\u00c9CATHLON 2002<\/p>","protected":false},"featured_media":33335,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-2574","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AG2R (b) PREVOYANCE-DECATHLON   2002   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/ag2r-decathlon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AG2R (b) PREVOYANCE-DECATHLON   2002   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"AG2R\u00a0 PREVOYANCE-DECATHLON 2002\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/ag2r-decathlon\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:38:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_1961-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/ag2r-decathlon\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/ag2r-decathlon\\\/\",\"name\":\"AG2R (b) PREVOYANCE-DECATHLON 2002 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/ag2r-decathlon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/ag2r-decathlon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_1961-scaled.jpg\",\"datePublished\":\"2023-01-24T17:51:38+00:00\",\"dateModified\":\"2026-05-13T13:38:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/ag2r-decathlon\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/ag2r-decathlon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/ag2r-decathlon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_1961-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_1961-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"AG2R PREVOYANCE-DECATHLON 2002\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/it\\\/retro-wielershirt\\\/ag2r-decathlon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"AG2R (b) PREVOYANCE-DECATHLON 2002 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AG2R (b) MAILLOT DE CYCLISME PREVOYANCE-DECATHLON 2002 - Maillots Ton Merckx - Tour \u00e0 travers le monde des maillots de cyclisme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/ag2r-decathlon\/","og_locale":"fr_FR","og_type":"article","og_title":"AG2R (b) PREVOYANCE-DECATHLON   2002   WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"AG2R\u00a0 PREVOYANCE-DECATHLON 2002","og_url":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/ag2r-decathlon\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:38:48+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_1961-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/ag2r-decathlon\/","url":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/ag2r-decathlon\/","name":"AG2R (b) MAILLOT DE CYCLISME PREVOYANCE-DECATHLON 2002 - Maillots Ton Merckx - Tour \u00e0 travers le monde des maillots de cyclisme","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/ag2r-decathlon\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/ag2r-decathlon\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_1961-scaled.jpg","datePublished":"2023-01-24T17:51:38+00:00","dateModified":"2026-05-13T13:38:48+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/ag2r-decathlon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/ag2r-decathlon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/ag2r-decathlon\/#primaryimage","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_1961-scaled.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_1961-scaled.jpg","width":1920,"height":2560,"caption":"AG2R PREVOYANCE-DECATHLON 2002"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/it\/retro-wielershirt\/ag2r-decathlon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"AG2R (b) PREVOYANCE-DECATHLON 2002 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Chemises de cyclisme Ton Merckx - Tour \u00e0 travers le monde des chemises de cyclisme","description":"des milliers de maillots de cyclisme originaux - commandez votre r\u00e9plique !","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Chemises de cyclisme Ton Merckx - Tour \u00e0 travers le monde des chemises de cyclisme","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/product\/2574","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/media\/33335"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/media?parent=2574"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/product_brand?post=2574"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/product_cat?post=2574"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/product_tag?post=2574"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}