{"id":1427,"date":"2023-01-24T17:38:18","date_gmt":"2023-01-24T17:38:18","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/lotto-adecco\/"},"modified":"2026-05-13T15:39:35","modified_gmt":"2026-05-13T13:39:35","slug":"loto-adecco","status":"publish","type":"product","link":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/retro-wielershirt\/lotto-adecco\/","title":{"rendered":"LOTTO (j)-ADECCO-GT 2001 CHEMISE DE CYCLISME"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1426,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-1427","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LOTTO (j)-ADECCO-GT  2001                                  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/lotto-adecco\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LOTTO (j)-ADECCO-GT  2001                                  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/lotto-adecco\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:39:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/SSA43053.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/lotto-adecco\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/lotto-adecco\\\/\",\"name\":\"LOTTO (j)-ADECCO-GT 2001 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/lotto-adecco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/lotto-adecco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43053.jpg\",\"datePublished\":\"2023-01-24T17:38:18+00:00\",\"dateModified\":\"2026-05-13T13:39:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/lotto-adecco\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/lotto-adecco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/lotto-adecco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43053.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA43053.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/pt\\\/retro-wielershirt\\\/lotto-adecco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LOTTO (j)-ADECCO-GT 2001 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LOTTO (j)-ADECCO-GT 2001 CHEMISE DE CYCLISME - Maillots de cyclisme Ton Merckx - Tour \u00e0 travers le monde des maillots de cyclisme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/lotto-adecco\/","og_locale":"fr_FR","og_type":"article","og_title":"LOTTO (j)-ADECCO-GT  2001                                  WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/lotto-adecco\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:39:35+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/SSA43053.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/lotto-adecco\/","url":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/lotto-adecco\/","name":"LOTTO (j)-ADECCO-GT 2001 CHEMISE DE CYCLISME - Maillots de cyclisme Ton Merckx - Tour \u00e0 travers le monde des maillots de cyclisme","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/lotto-adecco\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/lotto-adecco\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/SSA43053.jpg","datePublished":"2023-01-24T17:38:18+00:00","dateModified":"2026-05-13T13:39:35+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/lotto-adecco\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/lotto-adecco\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/lotto-adecco\/#primaryimage","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/SSA43053.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/SSA43053.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/pt\/retro-wielershirt\/lotto-adecco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"LOTTO (j)-ADECCO-GT 2001 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Chemises de cyclisme Ton Merckx - Tour \u00e0 travers le monde des chemises de cyclisme","description":"des milliers de maillots de cyclisme originaux - commandez votre r\u00e9plique !","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Chemises de cyclisme Ton Merckx - Tour \u00e0 travers le monde des chemises de cyclisme","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/product\/1427","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/media\/1426"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/media?parent=1427"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/product_brand?post=1427"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/product_cat?post=1427"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/fr\/wp-json\/wp\/v2\/product_tag?post=1427"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}