{"id":713,"date":"2023-01-24T17:29:48","date_gmt":"2023-01-24T17:29:48","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/onder-21-klassement\/"},"modified":"2026-05-13T15:40:06","modified_gmt":"2026-05-13T13:40:06","slug":"u21-klassifizierung","status":"publish","type":"product","link":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirt\/onder-21-klassement\/","title":{"rendered":"BOLAND BANK TOUR \u2013 KLASSIFIZIERUNG UNTER 21 \u2013 1995 \u2013 RADFAHRER-HEMD"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":712,"template":"","meta":[],"product_brand":[],"product_cat":[54],"product_tag":[],"class_list":["post-713","product","type-product","status-publish","has-post-thumbnail","product_cat-leiderstruien","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BOLAND BANK TOUR - ONDER 21 KLASSEMENT - 1995 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/onder-21-klassement\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BOLAND BANK TOUR - ONDER 21 KLASSEMENT - 1995 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/onder-21-klassement\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:40:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/SSA44073.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1704\" \/>\n\t<meta property=\"og:image:height\" content=\"2272\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/onder-21-klassement\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/onder-21-klassement\\\/\",\"name\":\"BOLAND BANK TOUR - ONDER 21 KLASSEMENT - 1995 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/onder-21-klassement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/onder-21-klassement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA44073.jpg\",\"datePublished\":\"2023-01-24T17:29:48+00:00\",\"dateModified\":\"2026-05-13T13:40:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/onder-21-klassement\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/onder-21-klassement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/onder-21-klassement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA44073.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/SSA44073.jpg\",\"width\":1704,\"height\":2272},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/en\\\/retro-wielershirt\\\/onder-21-klassement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"BOLAND BANK TOUR &#8211; ONDER 21 KLASSEMENT &#8211; 1995 &#8211; WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BOLAND BANK TOUR \u2013 KLASSIFIZIERUNG UNTER 21 \u2013 1995 \u2013 RADFAHRER-HEMD \u2013 Ton Merckx Radtrikots \u2013 Tour durch die Welt der Radsport-Trikots","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/onder-21-klassement\/","og_locale":"de_DE","og_type":"article","og_title":"BOLAND BANK TOUR - ONDER 21 KLASSEMENT - 1995 - WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/onder-21-klassement\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:40:06+00:00","og_image":[{"width":1704,"height":2272,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/SSA44073.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/onder-21-klassement\/","url":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/onder-21-klassement\/","name":"BOLAND BANK TOUR \u2013 KLASSIFIZIERUNG UNTER 21 \u2013 1995 \u2013 RADFAHRER-HEMD \u2013 Ton Merckx Radtrikots \u2013 Tour durch die Welt der Radsport-Trikots","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/onder-21-klassement\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/onder-21-klassement\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/SSA44073.jpg","datePublished":"2023-01-24T17:29:48+00:00","dateModified":"2026-05-13T13:40:06+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/onder-21-klassement\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/onder-21-klassement\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/onder-21-klassement\/#primaryimage","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/SSA44073.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/SSA44073.jpg","width":1704,"height":2272},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/en\/retro-wielershirt\/onder-21-klassement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"BOLAND BANK TOUR &#8211; ONDER 21 KLASSEMENT &#8211; 1995 &#8211; WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","description":"Tausende originale Radtrikots \u2013 bestellen Sie Ihr Replikat!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product\/713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/media\/712"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/media?parent=713"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product_brand?post=713"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product_cat?post=713"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product_tag?post=713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}