{"id":1928,"date":"2023-01-24T17:43:40","date_gmt":"2023-01-24T17:43:40","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/velda-flandria-lano\/"},"modified":"2026-05-13T15:39:14","modified_gmt":"2026-05-13T13:39:14","slug":"velda-flandria-lano","status":"publish","type":"product","link":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirt\/velda-flandria-lano\/","title":{"rendered":"VELDA(c)-FLANDRIA-LANO 1978 RADFAHREN-HEMD"},"content":{"rendered":"<p>VELDA(b)-FLANDRIA-LANO 1978.<\/p>\n<p>H\u00f6chstwahrscheinlich eine schlechte Nachbildung des Original-Shirts.<\/p>","protected":false},"excerpt":{"rendered":"<p>VELDA(b)-FLANDRIA-LANO 1978. H\u00f6chstwahrscheinlich eine schlechte Nachbildung des Originaltrikots.<\/p>","protected":false},"featured_media":177263,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-1928","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VELDA(c)-FLANDRIA-LANO  1978                              WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mail.replica-cycling.com\/ja\/retro-wielershirt\/velda-flandria-lano\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VELDA(c)-FLANDRIA-LANO  1978                              WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"VELDA(b)-FLANDRIA-LANO 1978. Veel kans een slechte Replica van het originele shirt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mail.replica-cycling.com\/ja\/retro-wielershirt\/velda-flandria-lano\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:39:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_4264-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/retro-wielershirt\\\/velda-flandria-lano\\\/\",\"url\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/retro-wielershirt\\\/velda-flandria-lano\\\/\",\"name\":\"VELDA(c)-FLANDRIA-LANO 1978 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/retro-wielershirt\\\/velda-flandria-lano\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/retro-wielershirt\\\/velda-flandria-lano\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4264-scaled.jpg\",\"datePublished\":\"2023-01-24T17:43:40+00:00\",\"dateModified\":\"2026-05-13T13:39:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/retro-wielershirt\\\/velda-flandria-lano\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/retro-wielershirt\\\/velda-flandria-lano\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/retro-wielershirt\\\/velda-flandria-lano\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4264-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4264-scaled.jpg\",\"width\":1920,\"height\":2560,\"caption\":\"VELDA-FLANDRIA-LANO 1978\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mail.replica-cycling.com\\\/ja\\\/retro-wielershirt\\\/velda-flandria-lano\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"VELDA(c)-FLANDRIA-LANO 1978 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VELDA(c)-FLANDRIA-LANO 1978 RADTRIKOT - Ton Merckx Radtrikots - Eine Reise durch die Welt der Radtrikots","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mail.replica-cycling.com\/ja\/retro-wielershirt\/velda-flandria-lano\/","og_locale":"de_DE","og_type":"article","og_title":"VELDA(c)-FLANDRIA-LANO  1978                              WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"VELDA(b)-FLANDRIA-LANO 1978. Veel kans een slechte Replica van het originele shirt.","og_url":"https:\/\/mail.replica-cycling.com\/ja\/retro-wielershirt\/velda-flandria-lano\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:39:14+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/mail.replica-cycling.com\/wp-content\/uploads\/2023\/01\/IMG_4264-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/mail.replica-cycling.com\/ja\/retro-wielershirt\/velda-flandria-lano\/","url":"https:\/\/mail.replica-cycling.com\/ja\/retro-wielershirt\/velda-flandria-lano\/","name":"VELDA(c)-FLANDRIA-LANO 1978 RADTRIKOT - Ton Merckx Radtrikots - Eine Reise durch die Welt der Radtrikots","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/retro-wielershirt\/velda-flandria-lano\/#primaryimage"},"image":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/retro-wielershirt\/velda-flandria-lano\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_4264-scaled.jpg","datePublished":"2023-01-24T17:43:40+00:00","dateModified":"2026-05-13T13:39:14+00:00","breadcrumb":{"@id":"https:\/\/mail.replica-cycling.com\/ja\/retro-wielershirt\/velda-flandria-lano\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mail.replica-cycling.com\/ja\/retro-wielershirt\/velda-flandria-lano\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mail.replica-cycling.com\/ja\/retro-wielershirt\/velda-flandria-lano\/#primaryimage","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_4264-scaled.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_4264-scaled.jpg","width":1920,"height":2560,"caption":"VELDA-FLANDRIA-LANO 1978"},{"@type":"BreadcrumbList","@id":"https:\/\/mail.replica-cycling.com\/ja\/retro-wielershirt\/velda-flandria-lano\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"VELDA(c)-FLANDRIA-LANO 1978 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","description":"Tausende originale Radtrikots \u2013 bestellen Sie Ihr Replikat!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product\/1928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/media\/177263"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/media?parent=1928"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product_brand?post=1928"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product_cat?post=1928"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product_tag?post=1928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}