{"id":1796,"date":"2023-01-24T17:42:11","date_gmt":"2023-01-24T17:42:11","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/sunweb-projob-randstad-2\/"},"modified":"2026-05-13T15:39:21","modified_gmt":"2026-05-13T13:39:21","slug":"sunweb-projob-randstad-2","status":"publish","type":"product","link":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirt\/sunweb-projob-randstad-2\/","title":{"rendered":"SUNWEB (e)-PROJOB-TEMPO TEAM 1. Shirt 2009 CYCLOCROSS-ANZUG"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":177576,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-1796","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SUNWEB (e)-PROJOB-TEMPO TEAM  1e shirt 2009  CYCLOCROSSPAK - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/sunweb-projob-randstad-2\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SUNWEB (e)-PROJOB-TEMPO TEAM  1e shirt 2009  CYCLOCROSSPAK - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/sunweb-projob-randstad-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:39:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/IMG_4670-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/sunweb-projob-randstad-2\\\/\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/sunweb-projob-randstad-2\\\/\",\"name\":\"SUNWEB (e)-PROJOB-TEMPO TEAM 1e shirt 2009 CYCLOCROSSPAK - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/sunweb-projob-randstad-2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/sunweb-projob-randstad-2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4670-scaled.jpg\",\"datePublished\":\"2023-01-24T17:42:11+00:00\",\"dateModified\":\"2026-05-13T13:39:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/sunweb-projob-randstad-2\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/sunweb-projob-randstad-2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/sunweb-projob-randstad-2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4670-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4670-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/sunweb-projob-randstad-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SUNWEB (e)-PROJOB-TEMPO TEAM 1e shirt 2009 CYCLOCROSSPAK\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SUNWEB (e)-PROJOB-TEMPO TEAM 1. Trikot 2009 CYCLOCROSS SUIT - Ton Merckx Radtrikots - Tour durch die Welt der Radtrikots","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/sunweb-projob-randstad-2\/","og_locale":"de_DE","og_type":"article","og_title":"SUNWEB (e)-PROJOB-TEMPO TEAM  1e shirt 2009  CYCLOCROSSPAK - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_url":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/sunweb-projob-randstad-2\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:39:21+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/IMG_4670-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/sunweb-projob-randstad-2\/","url":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/sunweb-projob-randstad-2\/","name":"SUNWEB (e)-PROJOB-TEMPO TEAM 1. Trikot 2009 CYCLOCROSS SUIT - Ton Merckx Radtrikots - Tour durch die Welt der Radtrikots","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/sunweb-projob-randstad-2\/#primaryimage"},"image":{"@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/sunweb-projob-randstad-2\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_4670-scaled.jpg","datePublished":"2023-01-24T17:42:11+00:00","dateModified":"2026-05-13T13:39:21+00:00","breadcrumb":{"@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/sunweb-projob-randstad-2\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/sunweb-projob-randstad-2\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/sunweb-projob-randstad-2\/#primaryimage","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_4670-scaled.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_4670-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/sunweb-projob-randstad-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"SUNWEB (e)-PROJOB-TEMPO TEAM 1e shirt 2009 CYCLOCROSSPAK"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","description":"Tausende originale Radtrikots \u2013 bestellen Sie Ihr Replikat!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product\/1796","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/media\/177576"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/media?parent=1796"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product_brand?post=1796"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product_cat?post=1796"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product_tag?post=1796"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}