{"id":1193,"date":"2023-01-24T17:35:52","date_gmt":"2023-01-24T17:35:52","guid":{"rendered":"https:\/\/ton.connectingminds.net\/product\/gbc-libertas\/"},"modified":"2026-05-13T15:39:45","modified_gmt":"2026-05-13T13:39:45","slug":"gbc-freiheit","status":"publish","type":"product","link":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirt\/gbc-libertas\/","title":{"rendered":"GBC-LIBERTAS 1963 RADFAHREN-HEMD"},"content":{"rendered":"<p>Die Teams GBC und LIBERTAS beschlossen am 1. April 1963, sich zusammenzuschlie\u00dfen.<\/p>\n<p>Von da an also das GBC-LIBERTAS-Team, zu dem dieses Shirt geh\u00f6rt.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die Teams GBC und LIBERTAS beschlossen am 1. April 1963, sich zusammenzuschlie\u00dfen. Von da an also das GBC-LIBERTAS-Team, zu dem dieses Shirt geh\u00f6rt.<\/p>","protected":false},"featured_media":177643,"template":"","meta":[],"product_brand":[],"product_cat":[151],"product_tag":[],"class_list":["post-1193","product","type-product","status-publish","has-post-thumbnail","product_cat-pro-team","first","onbackorder","taxable","shipping-taxable","purchasable","product-type-variable"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GBC-LIBERTAS   1963                                        WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/liberte-gbc\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GBC-LIBERTAS   1963                                        WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"og:description\" content=\"De ploegen GBC &amp; LIBERTAS besluiten op per 1 April 1963 te fuseren. Dus vanaf dan de GBC-LIBERTAS ploeg waarvan dit shirt is.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/liberte-gbc\/\" \/>\n<meta property=\"og:site_name\" content=\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-13T13:39:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/IMG_4733-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/liberte-gbc\\\/\",\"url\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/liberte-gbc\\\/\",\"name\":\"GBC-LIBERTAS 1963 WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/liberte-gbc\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/liberte-gbc\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4733-scaled.jpg\",\"datePublished\":\"2023-01-24T17:35:52+00:00\",\"dateModified\":\"2026-05-13T13:39:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/liberte-gbc\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/liberte-gbc\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/liberte-gbc\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4733-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/IMG_4733-scaled.jpg\",\"width\":1920,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/vintagecycling.store\\\/fr\\\/maillot-de-cyclisme-retro\\\/liberte-gbc\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Retro wielershirts\",\"item\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/de\\\/retro-wielershirts\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GBC-LIBERTAS 1963 WIELERSHIRT\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#website\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"description\":\"thousands of original cycling jerseys - order your replica!\",\"publisher\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#organization\",\"name\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\",\"url\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/mail.cyclingjerseys-originals.com\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/ton-merckx-logo.jpg\",\"width\":391,\"height\":57,\"caption\":\"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts\"},\"image\":{\"@id\":\"https:\\\/\\\/mail.cycling-originals.com\\\/pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GBC-LIBERTAS 1963 RADFAHREN-HEMD \u2013 Ton Merckx Radtrikots \u2013 Tour durch die Welt der Radtrikots","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/liberte-gbc\/","og_locale":"de_DE","og_type":"article","og_title":"GBC-LIBERTAS   1963                                        WIELERSHIRT - Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","og_description":"De ploegen GBC &amp; LIBERTAS besluiten op per 1 April 1963 te fuseren. Dus vanaf dan de GBC-LIBERTAS ploeg waarvan dit shirt is.","og_url":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/liberte-gbc\/","og_site_name":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts","article_modified_time":"2026-05-13T13:39:45+00:00","og_image":[{"width":1920,"height":2560,"url":"https:\/\/vintagecycling.store\/wp-content\/uploads\/2023\/01\/IMG_4733-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/liberte-gbc\/","url":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/liberte-gbc\/","name":"GBC-LIBERTAS 1963 RADFAHREN-HEMD \u2013 Ton Merckx Radtrikots \u2013 Tour durch die Welt der Radtrikots","isPartOf":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/liberte-gbc\/#primaryimage"},"image":{"@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/liberte-gbc\/#primaryimage"},"thumbnailUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_4733-scaled.jpg","datePublished":"2023-01-24T17:35:52+00:00","dateModified":"2026-05-13T13:39:45+00:00","breadcrumb":{"@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/liberte-gbc\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/liberte-gbc\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/liberte-gbc\/#primaryimage","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_4733-scaled.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/01\/IMG_4733-scaled.jpg","width":1920,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/vintagecycling.store\/fr\/maillot-de-cyclisme-retro\/liberte-gbc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/"},{"@type":"ListItem","position":2,"name":"Retro wielershirts","item":"https:\/\/mail.cyclingjerseys-originals.com\/de\/retro-wielershirts\/"},{"@type":"ListItem","position":3,"name":"GBC-LIBERTAS 1963 WIELERSHIRT"}]},{"@type":"WebSite","@id":"https:\/\/mail.cycling-originals.com\/pt\/#website","url":"https:\/\/mail.cycling-originals.com\/pt\/","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","description":"Tausende originale Radtrikots \u2013 bestellen Sie Ihr Replikat!","publisher":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mail.cycling-originals.com\/pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/mail.cycling-originals.com\/pt\/#organization","name":"Ton Merckx Radsport-Shirts \u2013 Tour durch die Welt der Radsport-Shirts","url":"https:\/\/mail.cycling-originals.com\/pt\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/","url":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","contentUrl":"https:\/\/mail.cyclingjerseys-originals.com\/wp-content\/uploads\/2023\/03\/ton-merckx-logo.jpg","width":391,"height":57,"caption":"Ton Merckx Wielershirts - Rondreis door de wereld van wielershirts"},"image":{"@id":"https:\/\/mail.cycling-originals.com\/pt\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product\/1193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/media\/177643"}],"wp:attachment":[{"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/media?parent=1193"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product_brand?post=1193"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product_cat?post=1193"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mail.cyclingjerseys-originals.com\/de\/wp-json\/wp\/v2\/product_tag?post=1193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}